{"id":3050,"date":"2022-11-09T10:48:33","date_gmt":"2022-11-09T09:48:33","guid":{"rendered":"https:\/\/www.caseificiolacava.com\/prodotti\/creme-chocolat\/"},"modified":"2023-05-17T15:58:35","modified_gmt":"2023-05-17T13:58:35","slug":"creme-chocolat","status":"publish","type":"product","link":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/","title":{"rendered":"Cr\u00e8me chocolat"},"content":{"rendered":"<p>Light and creamy, our soft dessert with chocolate cream retains the good taste of milk and cocoa.<br \/>\nWe prepare it with a few simple ingredients, with the main one being Sicilian milk from trusted farms in our territory. It comes in small 170 g jars and is ideal as a quick dessert or at the end of a meal.<\/p>\n<p><b>Ingredients<\/b><span style=\"font-weight: 400;\">: pasteurized MILK, mix for cr\u00e8me chocolat (sugar, corn starch, cocoa 22\/24 b.c., gelling agent: carrageenans E047, salt, flavorings).<\/span><\/p>\n<p><strong>Origin of milk<\/strong>: Italy &#8211; 100% Sicily<\/p>\n<p><b>Format<\/b><span style=\"font-weight: 400;\">: 170 gr<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soft chocolate dessert, made with fresh Sicilian milk and cocoa.<\/p>\n","protected":false},"featured_media":2284,"template":"","meta":{"_acf_changed":false,"content-type":"","_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[100],"product_tag":[],"class_list":{"0":"post-3050","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-yoghurt-and-soft-desserts","8":"first","9":"instock","10":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Creme Chocolat - Caseificio La Cava<\/title>\n<meta name=\"description\" content=\"Dessert al cucchiaio al cioccolato, o cr\u00e8me chocolat, preparato nel nostro caseificio con latte fresco proveniente da piccoli allevamenti siciliani.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Creme Chocolat - Caseificio La Cava\" \/>\n<meta property=\"og:description\" content=\"Dessert al cucchiaio al cioccolato, o cr\u00e8me chocolat, preparato nel nostro caseificio con latte fresco proveniente da piccoli allevamenti siciliani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/\" \/>\n<meta property=\"og:site_name\" content=\"Caseificio La Cava\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-17T13:58:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/prodotti\\\/creme-chocolat\\\/\",\"url\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/prodotti\\\/creme-chocolat\\\/\",\"name\":\"Creme Chocolat - Caseificio La Cava\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/prodotti\\\/creme-chocolat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/prodotti\\\/creme-chocolat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.caseificiolacava.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/creme-chocolat.jpg\",\"datePublished\":\"2022-11-09T09:48:33+00:00\",\"dateModified\":\"2023-05-17T13:58:35+00:00\",\"description\":\"Dessert al cucchiaio al cioccolato, o cr\u00e8me chocolat, preparato nel nostro caseificio con latte fresco proveniente da piccoli allevamenti siciliani.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/prodotti\\\/creme-chocolat\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/prodotti\\\/creme-chocolat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/prodotti\\\/creme-chocolat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.caseificiolacava.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/creme-chocolat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.caseificiolacava.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/creme-chocolat.jpg\",\"width\":799,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/prodotti\\\/creme-chocolat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.caseificiolacava.com\\\/?page_id=1795\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Yoghurt and soft desserts\",\"item\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/prodotti\\\/categoria\\\/yoghurt-and-soft-desserts\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cr\u00e8me chocolat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/\",\"name\":\"Caseificio La Cava\",\"description\":\"forma e formaggi di Sicilia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/#organization\",\"name\":\"Caseificio La Cava\",\"url\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.caseificiolacava.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-caseificio-lacava-small.png\",\"contentUrl\":\"https:\\\/\\\/www.caseificiolacava.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo-caseificio-lacava-small.png\",\"width\":170,\"height\":120,\"caption\":\"Caseificio La Cava\"},\"image\":{\"@id\":\"https:\\\/\\\/www.caseificiolacava.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Creme Chocolat - Caseificio La Cava","description":"Dessert al cucchiaio al cioccolato, o cr\u00e8me chocolat, preparato nel nostro caseificio con latte fresco proveniente da piccoli allevamenti siciliani.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/","og_locale":"en_US","og_type":"article","og_title":"Creme Chocolat - Caseificio La Cava","og_description":"Dessert al cucchiaio al cioccolato, o cr\u00e8me chocolat, preparato nel nostro caseificio con latte fresco proveniente da piccoli allevamenti siciliani.","og_url":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/","og_site_name":"Caseificio La Cava","article_modified_time":"2023-05-17T13:58:35+00:00","og_image":[{"width":799,"height":800,"url":"https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/","url":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/","name":"Creme Chocolat - Caseificio La Cava","isPartOf":{"@id":"https:\/\/www.caseificiolacava.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/#primaryimage"},"image":{"@id":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg","datePublished":"2022-11-09T09:48:33+00:00","dateModified":"2023-05-17T13:58:35+00:00","description":"Dessert al cucchiaio al cioccolato, o cr\u00e8me chocolat, preparato nel nostro caseificio con latte fresco proveniente da piccoli allevamenti siciliani.","breadcrumb":{"@id":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/#primaryimage","url":"https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg","contentUrl":"https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg","width":799,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/creme-chocolat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caseificiolacava.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.caseificiolacava.com\/?page_id=1795"},{"@type":"ListItem","position":3,"name":"Yoghurt and soft desserts","item":"https:\/\/www.caseificiolacava.com\/en\/prodotti\/categoria\/yoghurt-and-soft-desserts\/"},{"@type":"ListItem","position":4,"name":"Cr\u00e8me chocolat"}]},{"@type":"WebSite","@id":"https:\/\/www.caseificiolacava.com\/en\/#website","url":"https:\/\/www.caseificiolacava.com\/en\/","name":"Caseificio La Cava","description":"forma e formaggi di Sicilia","publisher":{"@id":"https:\/\/www.caseificiolacava.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caseificiolacava.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.caseificiolacava.com\/en\/#organization","name":"Caseificio La Cava","url":"https:\/\/www.caseificiolacava.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.caseificiolacava.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2021\/02\/logo-caseificio-lacava-small.png","contentUrl":"https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2021\/02\/logo-caseificio-lacava-small.png","width":170,"height":120,"caption":"Caseificio La Cava"},"image":{"@id":"https:\/\/www.caseificiolacava.com\/en\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg",799,800,false],"thumbnail":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat-150x125.jpg",150,125,true],"medium":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat-300x300.jpg",300,300,true],"medium_large":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat-768x769.jpg",768,769,true],"large":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg",799,800,false],"heading_ricetta":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg",649,650,false],"card_ricetta":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg",330,330,false],"1536x1536":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg",799,800,false],"2048x2048":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg",799,800,false],"product_single":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat-771x800.jpg",771,800,true],"product_loop":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat-480x560.jpg",480,560,true],"blog_loop":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat-600x600.jpg",600,600,true],"woocommerce_thumbnail":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat.jpg",799,800,false],"woocommerce_single":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat-771x772.jpg",771,772,true],"woocommerce_gallery_thumbnail":["https:\/\/www.caseificiolacava.com\/wp-content\/uploads\/2022\/11\/creme-chocolat-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"Filippo D'Angelo","author_link":"https:\/\/www.caseificiolacava.com\/en\/blog\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Soft chocolate dessert, made with fresh Sicilian milk and cocoa.","_links":{"self":[{"href":"https:\/\/www.caseificiolacava.com\/en\/wp-json\/wp\/v2\/product\/3050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caseificiolacava.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.caseificiolacava.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caseificiolacava.com\/en\/wp-json\/wp\/v2\/media\/2284"}],"wp:attachment":[{"href":"https:\/\/www.caseificiolacava.com\/en\/wp-json\/wp\/v2\/media?parent=3050"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.caseificiolacava.com\/en\/wp-json\/wp\/v2\/product_brand?post=3050"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.caseificiolacava.com\/en\/wp-json\/wp\/v2\/product_cat?post=3050"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.caseificiolacava.com\/en\/wp-json\/wp\/v2\/product_tag?post=3050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}